{"id":134,"count":1,"description":"<span style=\"font-weight: 400\">Caparr\u00f3s, una de las empresas del sector hortofrut\u00edcola l\u00edderes a nivel nacional de ventas al exterior, necesita una estrategia de comunicaci\u00f3n a la altura. Su confianza en Credo nos ha permitido fortalecer su presencia y mensaje de marca en canales de comunicaci\u00f3n online siguiendo principalmente tres pilares estrat\u00e9gicos: la calidad de su producci\u00f3n propia de origen nacional, su liderazgo en el mercado y su compromiso con la salud y la sostenibilidad. Trabajamos junto a la empresa almeriense l\u00edder en sand\u00eda y tomate para lograr grandes cosas y llevar la comunicaci\u00f3n de la marca a nuevos horizontes.<\/span>","link":"https:\/\/credo.si\/en\/clientes\/caparros\/","name":"Caparr\u00f3s","slug":"caparros","taxonomy":"clientes","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Caparr\u00f3s archivos - Credo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/credo.si\/clientes\/caparros\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caparr\u00f3s archivos\" \/>\n<meta property=\"og:description\" content=\"Caparr\u00f3s, una de las empresas del sector hortofrut\u00edcola l\u00edderes a nivel nacional de ventas al exterior, necesita una estrategia de comunicaci\u00f3n a la altura. Su confianza en Credo nos ha permitido fortalecer su presencia y mensaje de marca en canales de comunicaci\u00f3n online siguiendo principalmente tres pilares estrat\u00e9gicos: la calidad de su producci\u00f3n propia de origen nacional, su liderazgo en el mercado y su compromiso con la salud y la sostenibilidad. Trabajamos junto a la empresa almeriense l\u00edder en sand\u00eda y tomate para lograr grandes cosas y llevar la comunicaci\u00f3n de la marca a nuevos horizontes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/credo.si\/clientes\/caparros\/\" \/>\n<meta property=\"og:site_name\" content=\"Credo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@credotw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/credo.si\\\/clientes\\\/caparros\\\/\",\"url\":\"https:\\\/\\\/credo.si\\\/clientes\\\/caparros\\\/\",\"name\":\"Caparr\u00f3s archivos - Credo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/credo.si\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/credo.si\\\/clientes\\\/caparros\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/credo.si\\\/clientes\\\/caparros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/credo.si\\\/en\\\/bienvenida\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caparr\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/credo.si\\\/#website\",\"url\":\"https:\\\/\\\/credo.si\\\/\",\"name\":\"Credo\",\"description\":\"Estrategia \u00b7 Marketing \u00b7 Marca\",\"publisher\":{\"@id\":\"https:\\\/\\\/credo.si\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/credo.si\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/credo.si\\\/#organization\",\"name\":\"Credo\",\"url\":\"https:\\\/\\\/credo.si\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/credo.si\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/credo.si\\\/wp-content\\\/uploads\\\/Captura-de-Pantalla-2022-05-05-a-las-0.38.38.png\",\"contentUrl\":\"https:\\\/\\\/credo.si\\\/wp-content\\\/uploads\\\/Captura-de-Pantalla-2022-05-05-a-las-0.38.38.png\",\"width\":306,\"height\":204,\"caption\":\"Credo\"},\"image\":{\"@id\":\"https:\\\/\\\/credo.si\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/credofb\\\/\",\"https:\\\/\\\/x.com\\\/credotw\",\"https:\\\/\\\/www.instagram.com\\\/credo_si\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/credo-si\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Caparr\u00f3s archivos - Credo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/credo.si\/clientes\/caparros\/","og_locale":"en_US","og_type":"article","og_title":"Caparr\u00f3s archivos","og_description":"Caparr\u00f3s, una de las empresas del sector hortofrut\u00edcola l\u00edderes a nivel nacional de ventas al exterior, necesita una estrategia de comunicaci\u00f3n a la altura. Su confianza en Credo nos ha permitido fortalecer su presencia y mensaje de marca en canales de comunicaci\u00f3n online siguiendo principalmente tres pilares estrat\u00e9gicos: la calidad de su producci\u00f3n propia de origen nacional, su liderazgo en el mercado y su compromiso con la salud y la sostenibilidad. Trabajamos junto a la empresa almeriense l\u00edder en sand\u00eda y tomate para lograr grandes cosas y llevar la comunicaci\u00f3n de la marca a nuevos horizontes.","og_url":"https:\/\/credo.si\/clientes\/caparros\/","og_site_name":"Credo","twitter_card":"summary_large_image","twitter_site":"@credotw","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/credo.si\/clientes\/caparros\/","url":"https:\/\/credo.si\/clientes\/caparros\/","name":"Caparr\u00f3s archivos - Credo","isPartOf":{"@id":"https:\/\/credo.si\/#website"},"breadcrumb":{"@id":"https:\/\/credo.si\/clientes\/caparros\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/credo.si\/clientes\/caparros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/credo.si\/en\/bienvenida\/"},{"@type":"ListItem","position":2,"name":"Caparr\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/credo.si\/#website","url":"https:\/\/credo.si\/","name":"Credo","description":"Estrategia \u00b7 Marketing \u00b7 Marca","publisher":{"@id":"https:\/\/credo.si\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/credo.si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/credo.si\/#organization","name":"Credo","url":"https:\/\/credo.si\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/credo.si\/#\/schema\/logo\/image\/","url":"https:\/\/credo.si\/wp-content\/uploads\/Captura-de-Pantalla-2022-05-05-a-las-0.38.38.png","contentUrl":"https:\/\/credo.si\/wp-content\/uploads\/Captura-de-Pantalla-2022-05-05-a-las-0.38.38.png","width":306,"height":204,"caption":"Credo"},"image":{"@id":"https:\/\/credo.si\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/credofb\/","https:\/\/x.com\/credotw","https:\/\/www.instagram.com\/credo_si","https:\/\/www.linkedin.com\/company\/credo-si\/"]}]}},"_links":{"self":[{"href":"https:\/\/credo.si\/en\/wp-json\/wp\/v2\/clientes\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/credo.si\/en\/wp-json\/wp\/v2\/clientes"}],"about":[{"href":"https:\/\/credo.si\/en\/wp-json\/wp\/v2\/taxonomies\/clientes"}],"wp:post_type":[{"href":"https:\/\/credo.si\/en\/wp-json\/wp\/v2\/proyectos?clientes=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}